{"id":19227,"date":"2019-06-21T12:59:36","date_gmt":"2019-06-21T15:59:36","guid":{"rendered":"https:\/\/www.teatrodelbicentenariosanjuan.org\/?p=19227"},"modified":"2019-06-21T13:01:38","modified_gmt":"2019-06-21T16:01:38","slug":"principito-el-musical-que-deslumbrara-a-toda-la-familia-en-vacaciones-de-invierno","status":"publish","type":"post","link":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/novedades\/principito-el-musical-que-deslumbrara-a-toda-la-familia-en-vacaciones-de-invierno\/","title":{"rendered":"Principito, el musical que deslumbrar\u00e1 a toda la familia en vacaciones de invierno"},"content":{"rendered":"<p><strong>Una propuesta original e integradora para toda la familia. Este musical subir\u00e1 a escena el 12 y 13 de julio a las 18hs en el Teatro del Bicentenario.<\/strong><\/p>\n<p>\u00abPrincipito, el musical\u00bb es una adaptaci\u00f3n de la obra cl\u00e1sica de Antoine de Saint-Exup\u00e9ry publicada en 1943. Esta historia ha sido representada infinidad de veces en cine y teatro llegando a grandes y chicos.<\/p>\n<p>En esta oportunidad Acapella pondr\u00e1 en escena en el Teatro del Bicentenario una versi\u00f3n musical adaptada con creaci\u00f3n original en gui\u00f3n, m\u00fasica, letras y coreograf\u00edas. En la obra transcurren las diferentes aventuras que El Principito atraviesa en b\u00fasqueda de respuestas del mundo adulto sobre el ser humano y lo extra\u00f1o que son.<\/p>\n<h2>La obra<\/h2>\n<p><strong>\u201cPrincipito, el musical\u201d<\/strong><\/p>\n<p>Adaptaci\u00f3n original de la obra cl\u00e1sica de Antoine de Saint-Exup\u00e9ry<\/p>\n<p>Destinada a toda la familia<\/p>\n<p>Duraci\u00f3n del espect\u00e1culo: 60 minutos<\/p>\n<p>Entrada general: $250<\/p>","protected":false},"excerpt":{"rendered":"<p>Una propuesta original e integradora para toda la familia. Este musical subir\u00e1 a escena el 12 y 13 de julio a las 18hs en el Teatro del Bicentenario. \u00abPrincipito, el musical\u00bb es una adaptaci\u00f3n de la obra cl\u00e1sica de Antoine de Saint-Exup\u00e9ry publicada en 1943&#8230;.<\/p>","protected":false},"author":4,"featured_media":19229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[99],"tags":[],"class_list":["post-19227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/posts\/19227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/comments?post=19227"}],"version-history":[{"count":1,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/posts\/19227\/revisions"}],"predecessor-version":[{"id":19228,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/posts\/19227\/revisions\/19228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/media\/19229"}],"wp:attachment":[{"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/media?parent=19227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/categories?post=19227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teatrodelbicentenariosanjuan.org\/en\/wp-json\/wp\/v2\/tags?post=19227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}